{"id":10019298,"date":"2024-05-30T10:27:54","date_gmt":"2024-05-30T09:27:54","guid":{"rendered":"https:\/\/www.st-andrews.ac.uk\/arche\/?post_type=tribe_events&#038;p=11586"},"modified":"2025-05-27T08:39:09","modified_gmt":"2025-05-27T07:39:09","slug":"plenary-seminar-6","status":"publish","type":"tribe_events","link":"https:\/\/www.st-andrews.ac.uk\/arche\/event\/plenary-seminar-6\/2025-04-17\/","title":{"rendered":"Plenary Seminar:"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":44,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"tags":[],"tribe_events_cat":[54],"class_list":["post-10019298","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-plenary-session","cat_plenary-session","tribe-recurring-event","tribe-recurring-event-parent"],"_links":{"self":[{"href":"https:\/\/www.st-andrews.ac.uk\/arche\/wp-json\/wp\/v2\/tribe_events\/10019298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.st-andrews.ac.uk\/arche\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.st-andrews.ac.uk\/arche\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.st-andrews.ac.uk\/arche\/wp-json\/wp\/v2\/users\/44"}],"version-history":[{"count":0,"href":"https:\/\/www.st-andrews.ac.uk\/arche\/wp-json\/wp\/v2\/tribe_events\/10019298\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.st-andrews.ac.uk\/arche\/wp-json\/wp\/v2\/media?parent=10019298"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.st-andrews.ac.uk\/arche\/wp-json\/wp\/v2\/tags?post=10019298"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.st-andrews.ac.uk\/arche\/wp-json\/wp\/v2\/tribe_events_cat?post=10019298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}